{"id":4516,"date":"2012-10-15T08:11:43","date_gmt":"2012-10-15T08:11:43","guid":{"rendered":"http:\/\/www.pinoy-ofw.com\/directory\/2012\/10\/15\/western-union-locations-in-varna-bulgaria\/"},"modified":"2012-10-15T08:11:43","modified_gmt":"2012-10-15T08:11:43","slug":"western-union-locations-in-varna-bulgaria","status":"publish","type":"post","link":"https:\/\/www.pinoy-ofw.com\/directory\/western-union-locations-in-varna-bulgaria-4516.html","title":{"rendered":"Western Union Locations in Varna, Bulgaria"},"content":{"rendered":"<p><a href=\"http:\/\/pinoy-ofw.net\/directory\/wp-content\/uploads\/2012\/10\/western-union-logo26.webp\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4476\" title=\"western-union-logo\" src=\"http:\/\/pinoy-ofw.net\/directory\/wp-content\/uploads\/2012\/10\/western-union-logo26.webp\" alt=\"\" width=\"250\" height=\"119\" srcset=\"https:\/\/www.pinoy-ofw.com\/directory\/wp-content\/uploads\/sites\/12\/2012\/10\/western-union-logo26.webp 250w, https:\/\/www.pinoy-ofw.com\/directory\/wp-content\/uploads\/sites\/12\/2012\/10\/western-union-logo26-150x71.webp 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><strong>Western Union Locations in Varna, Bulgaria<\/strong><\/p>\n<p>FBK MODUS LTD<br \/>\n2 Musala Street<br \/>\nVarna, 9000<br \/>\n+359-52-621101<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EUROBANK EFG<br \/>\n100 8 Th Primorski Polk Ave.<br \/>\nVarna, 9000<br \/>\n+359-52-686959<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>FBK MODUS LTD<br \/>\nSheynovo Str.6<br \/>\nVarna, 9000<br \/>\n+359-52-616702<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EUROBANK EFG<br \/>\n82, Vladimir Varnenchi Blv.<br \/>\nVarna, 9000<br \/>\n+359-52-68975<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Western Union Locations in Varna, Bulgaria FBK MODUS LTD 2 Musala Street Varna, 9000 +359-52-621101 Money Transfer Mobile Money Transfer EUROBANK EFG 100 8 Th Primorski Polk Ave. Varna, 9000 +359-52-686959 Money Transfer Mobile Money Transfer FBK MODUS LTD Sheynovo Str.6 Varna, 9000 +359-52-616702 Money Transfer Mobile Money Transfer EUROBANK EFG 82, Vladimir Varnenchi Blv. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[213],"tags":[392,398],"class_list":{"0":"post-4516","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-bulgaria","7":"tag-bulgaria","8":"tag-varna"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/4516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/comments?post=4516"}],"version-history":[{"count":0,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/4516\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/media?parent=4516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/categories?post=4516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/tags?post=4516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}