{"id":29787,"date":"2023-04-22T07:05:44","date_gmt":"2023-04-22T07:05:44","guid":{"rendered":"http:\/\/www.pinoy-ofw.com\/directory\/?p=29787"},"modified":"2023-04-22T07:05:44","modified_gmt":"2023-04-22T07:05:44","slug":"ria-money-transfer-bulgaria","status":"publish","type":"post","link":"https:\/\/www.pinoy-ofw.com\/directory\/ria-money-transfer-bulgaria-29787.html","title":{"rendered":"Ria Money Transfer Bulgaria"},"content":{"rendered":"<ul>\n<li>Blagoevgrad<\/li>\n<li>Burgas<\/li>\n<li>Dobrich<\/li>\n<li>Gabrovo<\/li>\n<li>Haskovo<\/li>\n<li>Kardzhali<\/li>\n<li>Pazardzhik<\/li>\n<li>Pernik<\/li>\n<li>Pleven<\/li>\n<li>Plovdiv<\/li>\n<li>Razgrad<\/li>\n<li>Ruse<\/li>\n<li>Shumen<\/li>\n<li>Sliven<\/li>\n<li>Sofia<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Blagoevgrad Burgas Dobrich Gabrovo Haskovo Kardzhali Pazardzhik Pernik Pleven Plovdiv Razgrad Ruse Shumen Sliven Sofia &nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-29787","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/29787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/comments?post=29787"}],"version-history":[{"count":0,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/29787\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/media?parent=29787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/categories?post=29787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/tags?post=29787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}