{"id":18488,"date":"2016-10-03T01:03:59","date_gmt":"2016-10-03T01:03:59","guid":{"rendered":"http:\/\/www.pinoy-ofw.com\/directory\/?p=18488"},"modified":"2016-10-03T01:03:59","modified_gmt":"2016-10-03T01:03:59","slug":"ria-money-transfer-branches-in-asuncion-paraguay","status":"publish","type":"post","link":"https:\/\/www.pinoy-ofw.com\/directory\/ria-money-transfer-branches-in-asuncion-paraguay-18488.html","title":{"rendered":"Ria Money Transfer Branches in Asuncion, Paraguay"},"content":{"rendered":"<p>Banco Familiar Brios SAECA (Artigas)<br \/>\nAve. Artigas Esq. Ave. Santisima Trinidad<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Casa Matriz)<br \/>\nChile 1080 Esq. Jejui<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Centro)<br \/>\n25 De Mayo Esq. Iturbe<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Espana)<br \/>\nAve. EspaNa No. 1039 C. Washington<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Lider IV)<br \/>\nEstrella 692 C. O Leary<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Multiplaza)<br \/>\nAve. Eusebio Ayala, Bloque A, Planta Baja<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Palma)<br \/>\nPalma 202 Esq. Ntra. Sra. De La Asuncion<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Pettirossi)<br \/>\nAve. Pettirossi Esq. Mayor Fleitas<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Pinoza)<br \/>\nAve. Eusebio Ayala Y Bomberos Voluntarios<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Salemma Carmelitas)<br \/>\nAve. San Martin<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Salemma Multiplaza)<br \/>\nTeresa Lamas Carissimo<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00<br \/>\nBanco Familiar Brios SAECA (San Martin)<br \/>\nAve. Lilio Y San Martin<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Terminal)<br \/>\nAve. Fdo. De La Mora Esq. Taruma<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Banco Familiar Brios SAECA (Villa Morra)<br \/>\nMariscal Lopez Y Cruz Del Chaco<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Vision Banco S.A. (5ta Avenida)<br \/>\nAvda Acuna de Figueroa esq Parapiti<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 16:45 <\/p>\n<p>Vision Banco S.A. (Artigas)<br \/>\nAvenida Artigas c\/ Brasil<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 16:45 <\/p>\n<p>Vision Banco S.A.- Bank Deposit (Bank Deposit)<br \/>\nAv. Sta. Teresa 3088 esq. Consejal Vargas<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 16:45 <\/p>\n<p>Vision Banco S.A. (Bank Deposit)<br \/>\nAv. Sta. Teresa 3088 esq. Consejal Vargas<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 16:45 <\/p>\n<p>Banco Familiar Brios SAECA (Bank Deposit &#8211; Banco Familiar)<br \/>\nMariscal Lopez 3653<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 17:00<br \/>\nSat  08:00 &#8211; 12:00 <\/p>\n<p>Vision Banco S.A. (Casa Matriz)<br \/>\nAve. Sta. Teresa 3088 esq. Concejal Vargas<br \/>\nAsuncion AS<br \/>\nHours &amp; Information<br \/>\nMon &#8211; Fri  08:00 &#8211; 16:45<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Banco Familiar Brios SAECA (Artigas) Ave. Artigas Esq. Ave. Santisima Trinidad Asuncion AS Hours &amp; Information Mon &#8211; Fri 08:00 &#8211; 17:00 Sat 08:00 &#8211; 12:00 Banco Familiar Brios SAECA (Casa Matriz) Chile 1080 Esq. Jejui Asuncion AS Hours &amp; Information Mon &#8211; Fri 08:00 &#8211; 17:00 Sat 08:00 &#8211; 12:00 Banco Familiar Brios SAECA [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-18488","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-uncategorized"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/18488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/comments?post=18488"}],"version-history":[{"count":0,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/18488\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/media?parent=18488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/categories?post=18488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/tags?post=18488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}