{"id":1595,"date":"2012-01-03T05:33:42","date_gmt":"2012-01-03T05:33:42","guid":{"rendered":"http:\/\/www.pinoy-ofw.com\/directory\/2012\/01\/03\/western-union-al-ain-uae\/"},"modified":"2012-01-03T05:33:42","modified_gmt":"2012-01-03T05:33:42","slug":"western-union-al-ain-uae","status":"publish","type":"post","link":"https:\/\/www.pinoy-ofw.com\/directory\/western-union-al-ain-uae-1595.html","title":{"rendered":"Western Union Al Ain, UAE"},"content":{"rendered":"<p><strong>Western Union Locations in Al Ain, UAE<\/strong><\/p>\n<p>AL ANSARI EXCHANGE<br \/>\nAl Ain Airport<br \/>\nAl Ain,<br \/>\n+971-3-7854130<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EMIRATES POST<br \/>\nAlsenaia Branch<br \/>\nAlsenaia Al Ain<br \/>\nAl Ain, 7000<br \/>\n+971-3-7212645<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>AL FARDAN EXCHANGE<br \/>\nLulu Centre Sanaya<br \/>\nLulu Hypermarket Al Sanaiya<br \/>\nAl Ain,<br \/>\n+971-3-7211123<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EMIRATES POST<br \/>\nAlwegen Branch<br \/>\nAlwegen Area<br \/>\nAl Ain, 7000<br \/>\n+971-3-7351151<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EMIRATES POST<br \/>\nAl Hair Branch<br \/>\nAl Hair Alheer Al Ain<br \/>\nAl Ain, 7000<br \/>\n+971-3-7321140<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EMIRATES POST<br \/>\nAdministrative Centre Post Off<br \/>\nAl Ain, 99999<br \/>\n+971-3-7639225<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EMIRATES POST<br \/>\nAlyahaar<br \/>\nAlyahaaar Branch Al Ain<br \/>\nAl Ain, 17444<br \/>\n+971-03-7321140<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>EMIRATES POST<br \/>\nAlswaihan Branch<br \/>\nAlswaihan Al Ain<br \/>\nAl Ain, 7000<br \/>\n+971-3-7347167<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>AL FARDAN EXCHANGE<br \/>\nAl Yahar North Al Yahar<br \/>\nAl Ain,<br \/>\n+971-3-7827001<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n<p>AL FARDAN EXCHANGE<br \/>\nOpp Bank Of Baroda Town Planning<br \/>\nRoadclock Tower Al Ain<br \/>\nAl Ain,<br \/>\n+971-3-7554325<br \/>\nMoney Transfer<br \/>\nMobile Money Transfer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Western Union Locations in Al Ain, UAE AL ANSARI EXCHANGE Al Ain Airport Al Ain, +971-3-7854130 Money Transfer Mobile Money Transfer EMIRATES POST Alsenaia Branch Alsenaia Al Ain Al Ain, 7000 +971-3-7212645 Money Transfer Mobile Money Transfer AL FARDAN EXCHANGE Lulu Centre Sanaya Lulu Hypermarket Al Sanaiya Al Ain, +971-3-7211123 Money Transfer Mobile Money Transfer [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[],"class_list":{"0":"post-1595","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-united-arab-emirates"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/1595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/comments?post=1595"}],"version-history":[{"count":0,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/posts\/1595\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/media?parent=1595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/categories?post=1595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pinoy-ofw.com\/directory\/wp-json\/wp\/v2\/tags?post=1595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}